{"id":179,"count":1,"description":"","link":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/tag\/belvoir-50-lvrexl-2594\/","name":"Belvoir 50 LVREXL 2594","slug":"belvoir-50-lvrexl-2594","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/tags\/179"}],"collection":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/posts?tags=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}