{"id":7,"count":1,"description":"","link":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/tag\/emerald-50-lvre-110\/","name":"Emerald 50 LVRE 110","slug":"emerald-50-lvre-110","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/tags\/7"}],"collection":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/coretec-designbodenbelag.treffpunkt-viersen.de\/index.php\/wp-json\/wp\/v2\/posts?tags=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}